{"id":3938,"date":"2023-01-20T09:41:55","date_gmt":"2023-01-20T08:41:55","guid":{"rendered":"https:\/\/plouguerneau.net\/?p=3938"},"modified":"2025-01-16T11:27:36","modified_gmt":"2025-01-16T10:27:36","slug":"mardi-17-janvier-poull-pri-et-treongar","status":"publish","type":"post","link":"https:\/\/appriou.bzh\/index.php\/2023\/01\/mardi-17-janvier-poull-pri-et-treongar\/","title":{"rendered":"Mardi 17 Janvier : Poull-Pri et Treongar"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Apr\u00e8s un d\u00e9but d&rsquo;ann\u00e9e douloureux suite au d\u00e9c\u00e8s de notre camarade, mardi nous \u00e9tions 14 \u00e0 braver les \u00e9l\u00e9ments : averses, vent et froid.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bienvenue \u00e0 notre nouvelle \u201crecrue\u201d Andr\u00e9 K.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Une \u00e9quipe a termin\u00e9 de d\u00e9fricher le chemin \u00e0 Poull Pri, il est actuellement difficilement praticable avec le cumul de pr\u00e9cipitation de ce dernier mois.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le reste du groupe a continu\u00e9 de d\u00e9gager le long du ruisseau \u00e0 treongar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Merci Crucq, JL, les JCs, Jos\u00e9, Benoit, Les Yvons, Andr\u00e9, Michel, Xavier, Bruno et Bob.<\/p>\n\n\n<p><iframe src=\"https:\/\/www.facebook.com\/plugins\/post.php?href=https%3A%2F%2Fwww.facebook.com%2Fbozec.bruno%2Fposts%2Fpfbid0DBErf9LpSLasp6Myk2doVCQDW82a4Tm6fCs2auBgtwTHLQxjf2vWESyNfoPs4Rnkl&amp;width=500&amp;show_text=true&amp;height=568&amp;appId\" style=\"border:none;overflow:hidden\" scrolling=\"no\" allowfullscreen=\"true\" allow=\"autoplay; clipboard-write; encrypted-media; picture-in-picture; web-share\" width=\"500\" height=\"568\" frameborder=\"0\"><\/iframe><\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"3932\" src=\"https:\/\/plouguerneau.net\/wp-content\/uploads\/2023\/01\/yvon-769x1024.jpg\" alt=\"\" class=\"wp-image-3932\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"3931\" src=\"https:\/\/appriou.bzh\/wp-content\/uploads\/2023\/01\/trio-768x1024.jpg\" alt=\"\" class=\"wp-image-3931\" srcset=\"https:\/\/appriou.bzh\/wp-content\/uploads\/2023\/01\/trio-768x1024.jpg 768w, https:\/\/appriou.bzh\/wp-content\/uploads\/2023\/01\/trio-1152x1536.jpg 1152w, https:\/\/appriou.bzh\/wp-content\/uploads\/2023\/01\/trio.jpg 1536w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"3930\" src=\"https:\/\/plouguerneau.net\/wp-content\/uploads\/2023\/01\/michel-769x1024.jpg\" alt=\"\" class=\"wp-image-3930\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"3929\" src=\"https:\/\/plouguerneau.net\/wp-content\/uploads\/2023\/01\/ddc-768x1024.jpg\" alt=\"\" class=\"wp-image-3929\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"3928\" src=\"https:\/\/plouguerneau.net\/wp-content\/uploads\/2023\/01\/dd-1024x769.jpg\" alt=\"\" class=\"wp-image-3928\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"3927\" src=\"https:\/\/plouguerneau.net\/wp-content\/uploads\/2023\/01\/cruq_tronc-768x1024.jpg\" alt=\"\" class=\"wp-image-3927\"\/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Apr\u00e8s un d\u00e9but d&rsquo;ann\u00e9e douloureux suite au d\u00e9c\u00e8s de notre camarade, mardi nous \u00e9tions 14 \u00e0 braver les \u00e9l\u00e9ments : averses, vent et froid. Bienvenue \u00e0 notre nouvelle \u201crecrue\u201d Andr\u00e9 [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":3931,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"footnotes":""},"categories":[174],"tags":[],"class_list":["post-3938","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-activites-2023"],"_links":{"self":[{"href":"https:\/\/appriou.bzh\/index.php\/wp-json\/wp\/v2\/posts\/3938","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/appriou.bzh\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/appriou.bzh\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/appriou.bzh\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/appriou.bzh\/index.php\/wp-json\/wp\/v2\/comments?post=3938"}],"version-history":[{"count":0,"href":"https:\/\/appriou.bzh\/index.php\/wp-json\/wp\/v2\/posts\/3938\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/appriou.bzh\/index.php\/wp-json\/wp\/v2\/media\/3931"}],"wp:attachment":[{"href":"https:\/\/appriou.bzh\/index.php\/wp-json\/wp\/v2\/media?parent=3938"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/appriou.bzh\/index.php\/wp-json\/wp\/v2\/categories?post=3938"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/appriou.bzh\/index.php\/wp-json\/wp\/v2\/tags?post=3938"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}